{"id":88255,"date":"2026-06-25T10:06:18","date_gmt":"2026-06-25T08:06:18","guid":{"rendered":"https:\/\/casinobeats.com\/de\/?p=88255"},"modified":"2026-06-25T10:06:20","modified_gmt":"2026-06-25T08:06:20","slug":"wsop-auf-halbzeitkurs-hall-of-fame-spannung-glaser-dominiert","status":"publish","type":"post","link":"https:\/\/casinobeats.com\/de\/2026\/06\/25\/wsop-auf-halbzeitkurs-hall-of-fame-spannung-glaser-dominiert\/","title":{"rendered":"WSOP auf Halbzeitkurs: Hall-of-Fame-Spannung, Glaser dominiert"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Las Vegas bleibt auch Ende Juni das Zentrum der Pokerwelt. Die <strong>World Series of Poker (WSOP)<\/strong> hat inzwischen die Halbzeitmarke erreicht, und der Mittwoch, 24. Juni 2026, lieferte gleich mehrere spannende Geschichten, \u00fcber die die Poker-Community heute diskutiert. Am heutigen Donnerstag starten zudem gleich zwei Championship-Kracher. In dieser Zwischenphase steigt auch die Anzahl der <a href=\"https:\/\/casinobeats.com\/de\/2026\/06\/17\/wsop-wetten-poker\/\">WSOP Wetten<\/a> auf den Main Event Final Table am 3-5. August.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Hall of Fame: Die Finalisten stehen fest<\/h2>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"497\" height=\"246\" src=\"https:\/\/casinobeats.com\/de\/wp-content\/uploads\/sites\/2\/2026\/06\/Shaun-Deeb-raeumt-bei-der-WSOP-ab.jpg\" alt=\"\" class=\"wp-image-88332\" srcset=\"https:\/\/casinobeats.com\/de\/wp-content\/uploads\/sites\/2\/2026\/06\/Shaun-Deeb-raeumt-bei-der-WSOP-ab.jpg 497w, https:\/\/casinobeats.com\/de\/wp-content\/uploads\/sites\/2\/2026\/06\/Shaun-Deeb-raeumt-bei-der-WSOP-ab-300x148.jpg 300w, https:\/\/casinobeats.com\/de\/wp-content\/uploads\/sites\/2\/2026\/06\/Shaun-Deeb-raeumt-bei-der-WSOP-ab-130x63.jpg 130w\" sizes=\"(max-width: 497px) 100vw, 497px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Einer der gr\u00f6\u00dften Momente des Tages war die Bekanntgabe der <strong>acht Finalisten f\u00fcr die Poker Hall of Fame 2026<\/strong>. Besonders viel Aufmerksamkeit erh\u00e4lt dabei Shaun Deeb, der sich \u00fcber Jahre hinweg als gef\u00fcrchteter High-Stakes- und Mixed-Game-Spezialist einen Namen gemacht hat.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wer letztlich in die Hall of Fame aufgenommen wird, erfahren Pokerfans allerdings erst sp\u00e4ter im Sommer w\u00e4hrend der \u00dcbertragung des Main-Event-Finaltisches. Bis dahin d\u00fcrfte die Diskussion und auch das Wetten auf den Finaltisch in der Szene weitergehen. Pokerwetten auf die WSOP sind vor allem bei <a href=\"https:\/\/casinobeats.com\/de\/wetten\/wettanbieter-ohne-oasis\/\">Wettanbietern ohne OASIS<\/a> m\u00f6glich.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Benny Glaser greift nach dem Poker Players Championship<\/h2>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"497\" height=\"252\" src=\"https:\/\/casinobeats.com\/de\/wp-content\/uploads\/sites\/2\/2026\/06\/Benny-Glaser-WSOP-2026-Poker.jpg\" alt=\"\" class=\"wp-image-88314\" srcset=\"https:\/\/casinobeats.com\/de\/wp-content\/uploads\/sites\/2\/2026\/06\/Benny-Glaser-WSOP-2026-Poker.jpg 497w, https:\/\/casinobeats.com\/de\/wp-content\/uploads\/sites\/2\/2026\/06\/Benny-Glaser-WSOP-2026-Poker-300x152.jpg 300w\" sizes=\"(max-width: 497px) 100vw, 497px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Im prestigetr\u00e4chtigen <strong>$50.000 Poker Players Championship <\/strong>wurde es ernst. Das Turnier gilt f\u00fcr viele Profis als eine der anspruchsvollsten Pr\u00fcfungen des gesamten WSOP-Kalenders, da zahlreiche Pokervarianten gemeistert werden m\u00fcssen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nach einem starken Spieltag hat sich<strong> <\/strong><a href=\"https:\/\/casinobeats.com\/de\/2026\/03\/11\/pokerstars-scoop-ueberschreitet-milliarde-preisgeld\/\">Benny Glaser<\/a> die F\u00fchrung gesichert und geht als Chipleader unter die letzten 15 Teilnehmer. Damit befindet sich der 37-J\u00e4hrige aus Southampton in England in einer hervorragenden Ausgangsposition, um einen weiteren bedeutenden WSOP-Titel seiner Karriere zu gewinnen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Super Seniors: Kelley Slay setzt sich ab<\/h2>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"500\" height=\"237\" src=\"https:\/\/casinobeats.com\/de\/wp-content\/uploads\/sites\/2\/2026\/06\/WSOP-Pokerspieler-Kelley-Slay.jpg\" alt=\"\" class=\"wp-image-88323\" srcset=\"https:\/\/casinobeats.com\/de\/wp-content\/uploads\/sites\/2\/2026\/06\/WSOP-Pokerspieler-Kelley-Slay.jpg 500w, https:\/\/casinobeats.com\/de\/wp-content\/uploads\/sites\/2\/2026\/06\/WSOP-Pokerspieler-Kelley-Slay-300x142.jpg 300w, https:\/\/casinobeats.com\/de\/wp-content\/uploads\/sites\/2\/2026\/06\/WSOP-Pokerspieler-Kelley-Slay-130x63.jpg 130w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Auch im <strong>Event #61<\/strong>, dem <strong>$1.000 Super Seniors Championship<\/strong>, wurde kr\u00e4ftig ausgesiebt. Nach Abschluss von Tag 2 sind nur noch 103 Spieler im Rennen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die beste Ausgangslage verschaffte sich Kelley Slay, der mehr als <strong>zwei Millionen Chips<\/strong> eint\u00fcten konnte und damit deutlich vor dem verbliebenen Feld liegt. Der Kampf um das Bracelet bleibt jedoch offen, denn bis zum Titelgewinn sind noch einige H\u00fcrden zu \u00fcberwinden.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">WSOP erreicht offiziellen Halbzeitstand<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Neben den sportlichen Schlagzeilen gab es auch einen organisatorischen Meilenstein zu feiern. Mit dem Ende des gestrigen Spieltags wurden bereits 57 der insgesamt <strong>100 geplanten Live-Bracelet-Events<\/strong> entschieden.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die WSOP 2026 hat damit offiziell ihre Halbzeit erreicht \u2013 und die gr\u00f6\u00dften Highlights des Sommers stehen vielen Fans zufolge erst noch bevor.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Das erwartet Sie heute: Zwei Championship-Events starten<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Der Donnerstag, 25. Juni, verspricht erneut hochklassige Action. Besonders im Fokus stehen zwei Championship-Turniere, die traditionell viele bekannte Namen anziehen.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Event #67: $10.000 Limit 2-7 Lowball Triple Draw Championship (6-Handed)<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Start:<\/strong> <strong>21:00 Uhr<\/strong> deutsche Zeit (12:00 Uhr Ortszeit); 25.6.2026<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dieses Turnier z\u00e4hlt zu den technisch anspruchsvollsten Wettbewerben der gesamten Serie. Die besten Mixed-Game-Spieler der Welt werden versuchen, sich fr\u00fch in eine gute Position zu bringen.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Event #68: Ladies No-Limit Hold&#8217;em Championship<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Start:<\/strong> <strong>23:00 Uhr <\/strong>deutsche Zeit (14:00 Uhr Ortszeit); 25.6.2026<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Das beliebte <strong>Ladies Championship<\/strong> kehrt ebenfalls zur\u00fcck. F\u00fcr Spielerinnen betr\u00e4gt das Buy-in 1.000 US-Dollar, w\u00e4hrend das Turnier grunds\u00e4tzlich als <strong>offenes 10.000-Dollar-Event<\/strong> ausgeschrieben ist. Das stark verg\u00fcnstigte Startgeld f\u00fcr Frauen soll die Teilnehmerzahl f\u00f6rdern und hat sich in den vergangenen Jahren als wichtiger Bestandteil des Turniers etabliert.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Ausblick<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">W\u00e4hrend im Poker Players Championship die Entscheidung n\u00e4her r\u00fcckt und die Super Seniors auf die hei\u00dfe Phase zusteuern, richten sich heute viele Blicke auf die beiden neu startenden Championships. Gleichzeitig sorgt die <strong>Bekanntgabe der Hall-of-Fame-Finalisten<\/strong> f\u00fcr zus\u00e4tzlichen Gespr\u00e4chsstoff.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Kurz gesagt: Die WSOP hat die Halbzeit erreicht, aber von Sommerpause kann in Las Vegas keine Rede sein. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las Vegas bleibt auch Ende Juni das Zentrum der Pokerwelt. Die World Series of Poker (WSOP) hat inzwischen die Halbzeitmarke erreicht, und der Mittwoch, 24. Juni 2026, lieferte gleich mehrere spannende Geschichten, \u00fcber die die Poker-Community heute diskutiert. Am heutigen Donnerstag starten zudem gleich zwei Championship-Kracher. In dieser Zwischenphase steigt auch die Anzahl der WSOP [&hellip;]<\/p>\n","protected":false},"author":291,"featured_media":88256,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_lmt_disableupdate":"yes","_lmt_disable":"","footnotes":""},"categories":[115],"tags":[],"class_list":["post-88255","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>WSOP auf Halbzeitkurs: Hall-of-Fame-Spannung, Glaser dominiert<\/title>\n<meta name=\"description\" content=\"Las Vegas bleibt auch Ende Juni das Zentrum der Pokerwelt. Die World Series of Poker (WSOP) hat inzwischen die Halbzeitmarke erreicht, und der Mittwoch, 24. Juni 2026, lieferte gleich mehrere spannende Geschichten, \u00fcber die die Poker-Community heute diskutiert.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/casinobeats.com\/de\/2026\/06\/25\/wsop-auf-halbzeitkurs-hall-of-fame-spannung-glaser-dominiert\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"WSOP auf Halbzeitkurs: Hall-of-Fame-Spannung, Glaser dominiert\" \/>\n<meta property=\"og:description\" content=\"Las Vegas bleibt auch Ende Juni das Zentrum der Pokerwelt. Die World Series of Poker (WSOP) hat inzwischen die Halbzeitmarke erreicht, und der Mittwoch, 24. Juni 2026, lieferte gleich mehrere spannende Geschichten, \u00fcber die die Poker-Community heute diskutiert.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/casinobeats.com\/de\/2026\/06\/25\/wsop-auf-halbzeitkurs-hall-of-fame-spannung-glaser-dominiert\/\" \/>\n<meta property=\"og:site_name\" content=\"CasinoBeats Deutschland\" \/>\n<meta property=\"article:published_time\" content=\"2026-06-25T08:06:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-25T08:06:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/casinobeats.com\/de\/wp-content\/uploads\/sites\/2\/2026\/06\/WSOP-2026-News-WSOP-auf-Halbzeitkurs-Hall-of-Fame-Spannung-Glaser-dominiert.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"952\" \/>\n\t<meta property=\"og:image:height\" content=\"637\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Bj\u00f6rn Scholz\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Bj\u00f6rn Scholz\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/casinobeats.com\/de\/2026\/06\/25\/wsop-auf-halbzeitkurs-hall-of-fame-spannung-glaser-dominiert\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/casinobeats.com\/de\/2026\/06\/25\/wsop-auf-halbzeitkurs-hall-of-fame-spannung-glaser-dominiert\/\"},\"author\":{\"name\":\"Bj\u00f6rn Scholz\",\"@id\":\"https:\/\/casinobeats.com\/de\/#\/schema\/person\/d96a18337e361c5d54b8718cb7f991af\"},\"headline\":\"WSOP auf Halbzeitkurs: Hall-of-Fame-Spannung, Glaser dominiert\",\"datePublished\":\"2026-06-25T08:06:18+00:00\",\"dateModified\":\"2026-06-25T08:06:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/casinobeats.com\/de\/2026\/06\/25\/wsop-auf-halbzeitkurs-hall-of-fame-spannung-glaser-dominiert\/\"},\"wordCount\":574,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/casinobeats.com\/de\/2026\/06\/25\/wsop-auf-halbzeitkurs-hall-of-fame-spannung-glaser-dominiert\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/casinobeats.com\/de\/wp-content\/uploads\/sites\/2\/2026\/06\/WSOP-2026-News-WSOP-auf-Halbzeitkurs-Hall-of-Fame-Spannung-Glaser-dominiert.jpg\",\"articleSection\":[\"News\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/casinobeats.com\/de\/2026\/06\/25\/wsop-auf-halbzeitkurs-hall-of-fame-spannung-glaser-dominiert\/#respond\"]}],\"copyrightYear\":\"2026\",\"copyrightHolder\":{\"@id\":\"https:\/\/casinobeats.com\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/casinobeats.com\/de\/2026\/06\/25\/wsop-auf-halbzeitkurs-hall-of-fame-spannung-glaser-dominiert\/\",\"url\":\"https:\/\/casinobeats.com\/de\/2026\/06\/25\/wsop-auf-halbzeitkurs-hall-of-fame-spannung-glaser-dominiert\/\",\"name\":\"WSOP auf Halbzeitkurs: Hall-of-Fame-Spannung, Glaser dominiert\",\"isPartOf\":{\"@id\":\"https:\/\/casinobeats.com\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/casinobeats.com\/de\/2026\/06\/25\/wsop-auf-halbzeitkurs-hall-of-fame-spannung-glaser-dominiert\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/casinobeats.com\/de\/2026\/06\/25\/wsop-auf-halbzeitkurs-hall-of-fame-spannung-glaser-dominiert\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/casinobeats.com\/de\/wp-content\/uploads\/sites\/2\/2026\/06\/WSOP-2026-News-WSOP-auf-Halbzeitkurs-Hall-of-Fame-Spannung-Glaser-dominiert.jpg\",\"datePublished\":\"2026-06-25T08:06:18+00:00\",\"dateModified\":\"2026-06-25T08:06:20+00:00\",\"author\":{\"@id\":\"https:\/\/casinobeats.com\/de\/#\/schema\/person\/d96a18337e361c5d54b8718cb7f991af\"},\"description\":\"Las Vegas bleibt auch Ende Juni das Zentrum der Pokerwelt. Die World Series of Poker (WSOP) hat inzwischen die Halbzeitmarke erreicht, und der Mittwoch, 24. Juni 2026, lieferte gleich mehrere spannende Geschichten, \u00fcber die die Poker-Community heute diskutiert.\",\"breadcrumb\":{\"@id\":\"https:\/\/casinobeats.com\/de\/2026\/06\/25\/wsop-auf-halbzeitkurs-hall-of-fame-spannung-glaser-dominiert\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/casinobeats.com\/de\/2026\/06\/25\/wsop-auf-halbzeitkurs-hall-of-fame-spannung-glaser-dominiert\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/casinobeats.com\/de\/2026\/06\/25\/wsop-auf-halbzeitkurs-hall-of-fame-spannung-glaser-dominiert\/#primaryimage\",\"url\":\"https:\/\/casinobeats.com\/de\/wp-content\/uploads\/sites\/2\/2026\/06\/WSOP-2026-News-WSOP-auf-Halbzeitkurs-Hall-of-Fame-Spannung-Glaser-dominiert.jpg\",\"contentUrl\":\"https:\/\/casinobeats.com\/de\/wp-content\/uploads\/sites\/2\/2026\/06\/WSOP-2026-News-WSOP-auf-Halbzeitkurs-Hall-of-Fame-Spannung-Glaser-dominiert.jpg\",\"width\":952,\"height\":637,\"caption\":\"WSOP 2026 News - WSOP auf Halbzeitkurs Hall-of-Fame-Spannung, Glaser dominiert.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/casinobeats.com\/de\/2026\/06\/25\/wsop-auf-halbzeitkurs-hall-of-fame-spannung-glaser-dominiert\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/casinobeats.com\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\",\"item\":\"https:\/\/casinobeats.com\/de\/news\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"WSOP auf Halbzeitkurs: Hall-of-Fame-Spannung, Glaser dominiert\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/casinobeats.com\/de\/#website\",\"url\":\"https:\/\/casinobeats.com\/de\/\",\"name\":\"CasinoBeats Deutschland\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/casinobeats.com\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/casinobeats.com\/de\/#\/schema\/person\/d96a18337e361c5d54b8718cb7f991af\",\"name\":\"Bj\u00f6rn Scholz\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/casinobeats.com\/de\/wp-content\/uploads\/sites\/2\/2026\/03\/avatar_user_291_1773392416-96x96.jpg\",\"url\":\"https:\/\/casinobeats.com\/de\/wp-content\/uploads\/sites\/2\/2026\/03\/avatar_user_291_1773392416-96x96.jpg\",\"contentUrl\":\"https:\/\/casinobeats.com\/de\/wp-content\/uploads\/sites\/2\/2026\/03\/avatar_user_291_1773392416-96x96.jpg\",\"caption\":\"Bj\u00f6rn Scholz\"},\"description\":\"Bj\u00f6rn begeisterte sich schon w\u00e4hrend seines Studiums f\u00fcr Online-Poker, Sportwetten und Casino-Spiele und hat viele Jahre lang seinen Lebensunterhalt durch Online-Poker bestritten. Seither ist er ein ausgewiesener Experte f\u00fcr Pokerfragen, Sportwetten, Casinos und alles, was dazu geh\u00f6rt.\",\"sameAs\":[\"https:\/\/www.linkedin.com\/in\/bjrn-scholz-57147721a\/\"],\"url\":\"https:\/\/casinobeats.com\/de\/author\/bjoern\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"WSOP auf Halbzeitkurs: Hall-of-Fame-Spannung, Glaser dominiert","description":"Las Vegas bleibt auch Ende Juni das Zentrum der Pokerwelt. Die World Series of Poker (WSOP) hat inzwischen die Halbzeitmarke erreicht, und der Mittwoch, 24. Juni 2026, lieferte gleich mehrere spannende Geschichten, \u00fcber die die Poker-Community heute diskutiert.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/casinobeats.com\/de\/2026\/06\/25\/wsop-auf-halbzeitkurs-hall-of-fame-spannung-glaser-dominiert\/","og_locale":"de_DE","og_type":"article","og_title":"WSOP auf Halbzeitkurs: Hall-of-Fame-Spannung, Glaser dominiert","og_description":"Las Vegas bleibt auch Ende Juni das Zentrum der Pokerwelt. Die World Series of Poker (WSOP) hat inzwischen die Halbzeitmarke erreicht, und der Mittwoch, 24. Juni 2026, lieferte gleich mehrere spannende Geschichten, \u00fcber die die Poker-Community heute diskutiert.","og_url":"https:\/\/casinobeats.com\/de\/2026\/06\/25\/wsop-auf-halbzeitkurs-hall-of-fame-spannung-glaser-dominiert\/","og_site_name":"CasinoBeats Deutschland","article_published_time":"2026-06-25T08:06:18+00:00","article_modified_time":"2026-06-25T08:06:20+00:00","og_image":[{"width":952,"height":637,"url":"https:\/\/casinobeats.com\/de\/wp-content\/uploads\/sites\/2\/2026\/06\/WSOP-2026-News-WSOP-auf-Halbzeitkurs-Hall-of-Fame-Spannung-Glaser-dominiert.jpg","type":"image\/jpeg"}],"author":"Bj\u00f6rn Scholz","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Bj\u00f6rn Scholz","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/casinobeats.com\/de\/2026\/06\/25\/wsop-auf-halbzeitkurs-hall-of-fame-spannung-glaser-dominiert\/#article","isPartOf":{"@id":"https:\/\/casinobeats.com\/de\/2026\/06\/25\/wsop-auf-halbzeitkurs-hall-of-fame-spannung-glaser-dominiert\/"},"author":{"name":"Bj\u00f6rn Scholz","@id":"https:\/\/casinobeats.com\/de\/#\/schema\/person\/d96a18337e361c5d54b8718cb7f991af"},"headline":"WSOP auf Halbzeitkurs: Hall-of-Fame-Spannung, Glaser dominiert","datePublished":"2026-06-25T08:06:18+00:00","dateModified":"2026-06-25T08:06:20+00:00","mainEntityOfPage":{"@id":"https:\/\/casinobeats.com\/de\/2026\/06\/25\/wsop-auf-halbzeitkurs-hall-of-fame-spannung-glaser-dominiert\/"},"wordCount":574,"commentCount":0,"image":{"@id":"https:\/\/casinobeats.com\/de\/2026\/06\/25\/wsop-auf-halbzeitkurs-hall-of-fame-spannung-glaser-dominiert\/#primaryimage"},"thumbnailUrl":"https:\/\/casinobeats.com\/de\/wp-content\/uploads\/sites\/2\/2026\/06\/WSOP-2026-News-WSOP-auf-Halbzeitkurs-Hall-of-Fame-Spannung-Glaser-dominiert.jpg","articleSection":["News"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/casinobeats.com\/de\/2026\/06\/25\/wsop-auf-halbzeitkurs-hall-of-fame-spannung-glaser-dominiert\/#respond"]}],"copyrightYear":"2026","copyrightHolder":{"@id":"https:\/\/casinobeats.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/casinobeats.com\/de\/2026\/06\/25\/wsop-auf-halbzeitkurs-hall-of-fame-spannung-glaser-dominiert\/","url":"https:\/\/casinobeats.com\/de\/2026\/06\/25\/wsop-auf-halbzeitkurs-hall-of-fame-spannung-glaser-dominiert\/","name":"WSOP auf Halbzeitkurs: Hall-of-Fame-Spannung, Glaser dominiert","isPartOf":{"@id":"https:\/\/casinobeats.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/casinobeats.com\/de\/2026\/06\/25\/wsop-auf-halbzeitkurs-hall-of-fame-spannung-glaser-dominiert\/#primaryimage"},"image":{"@id":"https:\/\/casinobeats.com\/de\/2026\/06\/25\/wsop-auf-halbzeitkurs-hall-of-fame-spannung-glaser-dominiert\/#primaryimage"},"thumbnailUrl":"https:\/\/casinobeats.com\/de\/wp-content\/uploads\/sites\/2\/2026\/06\/WSOP-2026-News-WSOP-auf-Halbzeitkurs-Hall-of-Fame-Spannung-Glaser-dominiert.jpg","datePublished":"2026-06-25T08:06:18+00:00","dateModified":"2026-06-25T08:06:20+00:00","author":{"@id":"https:\/\/casinobeats.com\/de\/#\/schema\/person\/d96a18337e361c5d54b8718cb7f991af"},"description":"Las Vegas bleibt auch Ende Juni das Zentrum der Pokerwelt. Die World Series of Poker (WSOP) hat inzwischen die Halbzeitmarke erreicht, und der Mittwoch, 24. Juni 2026, lieferte gleich mehrere spannende Geschichten, \u00fcber die die Poker-Community heute diskutiert.","breadcrumb":{"@id":"https:\/\/casinobeats.com\/de\/2026\/06\/25\/wsop-auf-halbzeitkurs-hall-of-fame-spannung-glaser-dominiert\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/casinobeats.com\/de\/2026\/06\/25\/wsop-auf-halbzeitkurs-hall-of-fame-spannung-glaser-dominiert\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/casinobeats.com\/de\/2026\/06\/25\/wsop-auf-halbzeitkurs-hall-of-fame-spannung-glaser-dominiert\/#primaryimage","url":"https:\/\/casinobeats.com\/de\/wp-content\/uploads\/sites\/2\/2026\/06\/WSOP-2026-News-WSOP-auf-Halbzeitkurs-Hall-of-Fame-Spannung-Glaser-dominiert.jpg","contentUrl":"https:\/\/casinobeats.com\/de\/wp-content\/uploads\/sites\/2\/2026\/06\/WSOP-2026-News-WSOP-auf-Halbzeitkurs-Hall-of-Fame-Spannung-Glaser-dominiert.jpg","width":952,"height":637,"caption":"WSOP 2026 News - WSOP auf Halbzeitkurs Hall-of-Fame-Spannung, Glaser dominiert."},{"@type":"BreadcrumbList","@id":"https:\/\/casinobeats.com\/de\/2026\/06\/25\/wsop-auf-halbzeitkurs-hall-of-fame-spannung-glaser-dominiert\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/casinobeats.com\/de\/"},{"@type":"ListItem","position":2,"name":"News","item":"https:\/\/casinobeats.com\/de\/news\/"},{"@type":"ListItem","position":3,"name":"WSOP auf Halbzeitkurs: Hall-of-Fame-Spannung, Glaser dominiert"}]},{"@type":"WebSite","@id":"https:\/\/casinobeats.com\/de\/#website","url":"https:\/\/casinobeats.com\/de\/","name":"CasinoBeats Deutschland","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/casinobeats.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/casinobeats.com\/de\/#\/schema\/person\/d96a18337e361c5d54b8718cb7f991af","name":"Bj\u00f6rn Scholz","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/casinobeats.com\/de\/wp-content\/uploads\/sites\/2\/2026\/03\/avatar_user_291_1773392416-96x96.jpg","url":"https:\/\/casinobeats.com\/de\/wp-content\/uploads\/sites\/2\/2026\/03\/avatar_user_291_1773392416-96x96.jpg","contentUrl":"https:\/\/casinobeats.com\/de\/wp-content\/uploads\/sites\/2\/2026\/03\/avatar_user_291_1773392416-96x96.jpg","caption":"Bj\u00f6rn Scholz"},"description":"Bj\u00f6rn begeisterte sich schon w\u00e4hrend seines Studiums f\u00fcr Online-Poker, Sportwetten und Casino-Spiele und hat viele Jahre lang seinen Lebensunterhalt durch Online-Poker bestritten. Seither ist er ein ausgewiesener Experte f\u00fcr Pokerfragen, Sportwetten, Casinos und alles, was dazu geh\u00f6rt.","sameAs":["https:\/\/www.linkedin.com\/in\/bjrn-scholz-57147721a\/"],"url":"https:\/\/casinobeats.com\/de\/author\/bjoern\/"}]}},"modified_by":"lena","_links":{"self":[{"href":"https:\/\/casinobeats.com\/de\/wp-json\/wp\/v2\/posts\/88255","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/casinobeats.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/casinobeats.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/casinobeats.com\/de\/wp-json\/wp\/v2\/users\/291"}],"replies":[{"embeddable":true,"href":"https:\/\/casinobeats.com\/de\/wp-json\/wp\/v2\/comments?post=88255"}],"version-history":[{"count":4,"href":"https:\/\/casinobeats.com\/de\/wp-json\/wp\/v2\/posts\/88255\/revisions"}],"predecessor-version":[{"id":88347,"href":"https:\/\/casinobeats.com\/de\/wp-json\/wp\/v2\/posts\/88255\/revisions\/88347"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/casinobeats.com\/de\/wp-json\/wp\/v2\/media\/88256"}],"wp:attachment":[{"href":"https:\/\/casinobeats.com\/de\/wp-json\/wp\/v2\/media?parent=88255"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/casinobeats.com\/de\/wp-json\/wp\/v2\/categories?post=88255"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/casinobeats.com\/de\/wp-json\/wp\/v2\/tags?post=88255"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}